{"id":1405,"date":"2020-06-26T13:30:07","date_gmt":"2020-06-26T09:30:07","guid":{"rendered":"https:\/\/www.rivistazoom.it\/?p=1405"},"modified":"2020-07-01T20:31:54","modified_gmt":"2020-07-01T18:31:54","slug":"tumori-tolto-il-freno-che-impedisce-di-aggredirli","status":"publish","type":"post","link":"https:\/\/www.rivistazoom.it\/index.php\/2020\/06\/26\/tumori-tolto-il-freno-che-impedisce-di-aggredirli\/","title":{"rendered":"Tumori, tolto il freno che impedisce di aggredirli"},"content":{"rendered":"\n<p>Un recente studio dell\u2019Universit\u00e0 di Yale, pubblicato su Nature, ha rivelato il segnale di disturbo che molti tumori producono per interferire nelle comunicazioni del sistema immunitario e rendersi inattaccabili.<\/p>\n\n\n\n<p>La ricerca, coordinata dall\u2019immunologo Aaron Ring, \u00e8 stata condotta sui topi: si \u00e8 scoperto che in diversi tumori sono presenti elevate quantit\u00e0 della proteina IL-18BP, che agisce come un <strong>segnale di interferenza nei confronti del sistema immunitario<\/strong>. Starebbe proprio nell\u2019azione di questa proteina la causa del fallimento di tutte le sperimentazioni cliniche provate come terapie anti-cancro: essa infatti lega e inattiva una molecola antinfiammatoria, chiamata interleuchina 18, impedendole di mobilitare un\u2019imponente risposta immunitaria.<\/p>\n\n\n\n<p>La risposta dei ricercatori \u00e8 stata la creazione di una variante di interleuchina 18 capace di non farsi bloccare da Il-18BP. Dopo averla somministrata ai topi, l\u2019interleuchina modificata ha indotto una <strong>drastica riduzione della crescita dei tumori<\/strong>, che addirittura in molti casi sono spariti del tutto.<\/p>\n\n\n\n<p>Dopo questi risultati, i ricercatori si sono gi\u00e0 messi all\u2019opera per cominciare i primi test clinici sull\u2019uomo entro il prossimo anno.<\/p>\n\n\n\n<p class=\"has-text-align-right\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"495\" height=\"330\" src=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/07\/155027011-50b7c91c-fdbd-41eb-b2c0-174dbe90e9c5.jpg\" alt=\"\" class=\"wp-image-1451\" srcset=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/07\/155027011-50b7c91c-fdbd-41eb-b2c0-174dbe90e9c5.jpg 495w, https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/07\/155027011-50b7c91c-fdbd-41eb-b2c0-174dbe90e9c5-300x200.jpg 300w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">Articolo a cura di <em>Fabrizio Scarf\u00f2<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un recente studio dell\u2019Universit\u00e0 di Yale, pubblicato su Nature, ha rivelato il segnale di disturbo che molti tumori producono per<\/p>\n<div class='the_champ_sharing_container the_champ_vertical_sharing the_champ_hide_sharing the_champ_bottom_sharing' style='width:44px;left: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-super-socializer-href=\"https:\/\/www.rivistazoom.it\"data-super-socializer-no-counts=\"1\"><div class=\"the_champ_sharing_ul\"><a style=\"font-size:24px!important;box-shadow:none;display:inline-block!important;font-size: 16px;padding: 0 4px;vertical-align:middle;display:inline;\" class=\"theChampSharingRound\"><span class=\"the_champ_square_count\">&nbsp;<\/span><div style=\"width:70px;height:35px;margin-bottom:9px !important;\" title=\"Total Shares\" class=\"theChampSharing theChampTCBackground\"><\/div><\/a><a class=\"the_champ_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#3c589a;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_facebook_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Zoom%20-%20&url=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg the_champ_s__default the_champ_s_twitter\" style=\"background-color:#55acee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_twitter_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Zoom%20-%20 https%3A%2F%2Fwww.rivistazoom.it\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#55eb4c;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_whatsapp_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"the_champ_svg_stroke the_champ_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"the_champ_no_fill the_champ_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_instagram\" href=\"https:\/\/www.instagram.com\/Rivista_Zoom\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#53beee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_instagram_count\">&nbsp;<\/span><svg style=\"display:block;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><\/div><\/div>","protected":false},"author":1,"featured_media":1404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[159,189,29,552],"_links":{"self":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/1405"}],"collection":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/comments?post=1405"}],"version-history":[{"count":2,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/1405\/revisions"}],"predecessor-version":[{"id":1452,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/1405\/revisions\/1452"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media\/1404"}],"wp:attachment":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media?parent=1405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/categories?post=1405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/tags?post=1405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}