{"id":4392,"date":"2021-03-12T21:00:00","date_gmt":"2021-03-12T20:00:00","guid":{"rendered":"https:\/\/www.rivistazoom.it\/?p=4392"},"modified":"2021-03-01T12:14:33","modified_gmt":"2021-03-01T11:14:33","slug":"a-caccia-di-alieni-dove-sono-tutti-quanti","status":"publish","type":"post","link":"https:\/\/www.rivistazoom.it\/index.php\/2021\/03\/12\/a-caccia-di-alieni-dove-sono-tutti-quanti\/","title":{"rendered":"A caccia di alieni \u2013 dove sono tutti quanti?"},"content":{"rendered":"\n<p>Solo nella nostra galassia ci sono almeno 200 miliardi di stelle, la stragrande maggioranza delle quali con pianeti potenzialmente abitabili, eppure non vola una mosca. Dove sono gli altri, perch\u00e9 non li troviamo, insomma possibile che non ci siano altre forme di vita sparse nell\u2019Universo? Dove sono tutti quanti? Questo \u00e8 il paradosso di Fermi.&nbsp;<\/p>\n\n\n\n<p>L\u2019et\u00e0 delle prime stromatoliti sulla Terra \u00e8 stimata intorno ai 3.5 miliardi di anni. Le stromatoliti sono rocce sedimentarie formate grazie all\u2019attivit\u00e0 di microorganismi fotosintetici. Queste ci dicono che la vita qui \u00e8 comparsa subito: non appena la Terra si \u00e8 raffreddata a sufficienza, ecco i primi batteri. Nonostante questa fretta di voler comparire subito, la vita ci ha riflettuto a lungo prima di evolversi in forme davvero interessanti ed intelligenti come noi.&nbsp;<\/p>\n\n\n\n<p>Per capirne la lentezza facciamo finta di condensare tutta la storia della vita sulla Terra in un anno solare partendo dal primo gennaio. Il 27 Maggio comparirebbero le prime cellule con un nucleo e fino alla fine di Ottobre, sulla Terra, non ci sarebbero altro che cellule sparse qua e l\u00e0 a riprodursi. Solo il 2 di Novembre comparirebbero i primi organismi pluricellulari, il 15\/11 le prime piante, il 24\/11 qualche sagace vertebrato inizierebbe a muoversi sulle terre emerse, il 9\/12 i primi dinosauri, questi scomparirebbero il 24\/12, il 31\/12 alle 10 del mattino avremmo la comparsa dell\u2019antenato comune tra noi e gli scimpanz\u00e8, alle 23:32 nascerebbe in Africa la specie Homo sapiens, alle 23:58:20 terminerebbe l\u2019ultima glaciazione e l\u2019uomo diventerebbe coltivatore [1]. La nostra storia, quella che studiamo sui libri dalle elementari, occuperebbe solo l\u2019ultimo minuto di questo anno cos\u00ec condensato.<\/p>\n\n\n\n<p>Se quindi la comparsa della vita pu\u00f2 essere un semplice processo chimico-fisico, e come tale allora ineluttabile ogniqualvolta si presentino nell\u2019universo le stesse condizioni della Terra primordiale, l\u2019evoluzione della vita in forme intelligenti potrebbe essere molto pi\u00f9 difficile. Per questo, di tutte le stelle che abbiamo in cielo, quelle che potrebbero ospitare sui loro pianeti esserini intelligenti, sono solo le stelle pi\u00f9 simili al sole: quelle quindi con una vita stabile lunga diversi miliardi di anni e necessaria a questa lenta evoluzione.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" width=\"512\" height=\"273\" src=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2021\/03\/Dove-sono-tutti-quanti.png\" alt=\"\" class=\"wp-image-4393\" srcset=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2021\/03\/Dove-sono-tutti-quanti.png 512w, https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2021\/03\/Dove-sono-tutti-quanti-300x160.png 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<p>Nonostante questo, di luoghi potenzialmente abitati da esseri intelligenti ce ne sarebbero comunque tanti. Dove sono allora tutti quanti? Perch\u00e9 non ci vengono a salutare? Che gli abbiamo fatto di male?<\/p>\n\n\n\n<p>La prima possibilit\u00e0 \u00e8 che effettivamente questo processo evolutivo, come avvenuto sulla Terra, sia qualcosa di altamente improbabile. Quasi una unicit\u00e0 la nostra storia.<\/p>\n\n\n\n<p>La seconda possibilit\u00e0 \u00e8 che pur esistendo, le varie civilt\u00e0 aliene siano troppo lontane da noi. Sicuramente affrontare un viaggio interstellare con navi sufficientemente grandi da ospitare un numero tale di individui utili a garantirne la continuit\u00e0 per anni, secoli, millenni \u00e8 un\u2019impresa davvero omerica. Ma comunicazioni radio sarebbero pi\u00f9 fattibili, perch\u00e9 pur stando in ascolto, non riceviamo nulla? Possibile che solo noi abbiamo raggiunto questo progresso tecnologico?<\/p>\n\n\n\n<p>Resta una terza possibilit\u00e0, pi\u00f9 un monito per noi che un\u2019appagante risposta al paradosso di Fermi: le civilt\u00e0 intelligenti sono altamente instabili. Solo le civilt\u00e0 pi\u00f9 intelligenti possono godere della stupidit\u00e0 necessaria all\u2019autodistruzione. Strutture sociali altamente complesse, guerre nucleari, armi batteriologiche, disastri ambientali, inquinamento incontrollato, e chi pi\u00f9 ne ha pi\u00f9 ne metta, sono con molta probabilit\u00e0 le uniche cause che possiamo individuare come responsabili di questa solitudine cosmica. Quando compaiono razze intelligenti, la loro esistenza, minata da scelte stupidamente pericolose, \u00e8 cos\u00ec breve da rendere molto improbabile l\u2019incontro temporale e spaziale con altre razze [2]. E questo, pi\u00f9 che portarci con la testa a ragionar di stelle, dovrebbe farci riflettere sul come trattiamo altri nostri simili e con quale cura ci occupiamo della nostra unica casa, il pianeta Terra. Da grandi poteri, derivano grandi responsabilit\u00e0\u2026&nbsp;<\/p>\n\n\n\n<p>Cieli sereni e stellati!<\/p>\n\n\n\n<p>Per saperne di pi\u00f9:<\/p>\n\n\n\n<p>[1] Storia compatta della vita \u2013 Deproducers : <a href=\"https:\/\/youtu.be\/5J_5Vrf-Dyg\">https:\/\/youtu.be\/5J_5Vrf-Dyg<\/a> \t<\/p>\n\n\n\n<p>[2] Paolo Saraceno: Il paradosso di Fermi Quaderno N\u00b04 di Ricerca Aerospaziale; IBN Editore marzo 2019 (www.ibneditore.it)<\/p>\n\n\n\n<p class=\"has-text-align-right\">Articolo a cura di Andrea Alimenti<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo nella nostra galassia ci sono almeno 200 miliardi di stelle, la stragrande maggioranza delle quali con pianeti potenzialmente abitabili,<\/p>\n<div class='the_champ_sharing_container the_champ_vertical_sharing the_champ_hide_sharing the_champ_bottom_sharing' style='width:44px;left: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-super-socializer-href=\"https:\/\/www.rivistazoom.it\"><div class=\"the_champ_sharing_ul\"><a style=\"font-size:24px!important;box-shadow:none;display:inline-block!important;font-size: 16px;padding: 0 4px;vertical-align:middle;display:inline;\" class=\"theChampSharingRound\"><span class=\"the_champ_square_count\">&nbsp;<\/span><div style=\"width:70px;height:35px;margin-bottom:9px !important;\" title=\"Total Shares\" class=\"theChampSharing theChampTCBackground\"><\/div><\/a><a class=\"the_champ_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#3c589a;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_facebook_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Zoom%20-%20&url=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg the_champ_s__default the_champ_s_twitter\" style=\"background-color:#55acee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_twitter_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Zoom%20-%20 https%3A%2F%2Fwww.rivistazoom.it\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#55eb4c;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_whatsapp_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"the_champ_svg_stroke the_champ_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"the_champ_no_fill the_champ_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_instagram\" href=\"https:\/\/www.instagram.com\/Rivista_Zoom\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#53beee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_instagram_count\">&nbsp;<\/span><svg style=\"display:block;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><\/div><\/div>","protected":false},"author":1,"featured_media":4393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[1195,1339,189,29,1345],"_links":{"self":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/4392"}],"collection":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/comments?post=4392"}],"version-history":[{"count":1,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/4392\/revisions"}],"predecessor-version":[{"id":4394,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/4392\/revisions\/4394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media\/4393"}],"wp:attachment":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media?parent=4392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/categories?post=4392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/tags?post=4392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}