{"id":901,"date":"2020-04-06T09:37:11","date_gmt":"2020-04-06T07:37:11","guid":{"rendered":"https:\/\/www.rivistazoom.it\/?p=901"},"modified":"2020-04-06T09:37:12","modified_gmt":"2020-04-06T07:37:12","slug":"lalbero-genealogico-di-lucio-battisti","status":"publish","type":"post","link":"https:\/\/www.rivistazoom.it\/index.php\/2020\/04\/06\/lalbero-genealogico-di-lucio-battisti\/","title":{"rendered":"L&#8217;ALBERO GENEALOGICO DI LUCIO BATTISTI"},"content":{"rendered":"\n<p>Il 5 marzo c&#8217;\u00e8 stato il compleanno di Lucio Battisti (Poggio Bustone, 5 marzo 1943 \u2013 Milano, 9 settembre 1998) cantautore, compositore, polistrumentista, arrangiatore e produttore discografico italiano.<br>Tra i pi\u00f9 importanti, influenti e innovativi cantanti e musicisti italiani, \u00e8 considerato una delle massime personalit\u00e0 nella storia della musica italiana sia come compositore e interprete dei suoi brani, sia come compositore per altri artisti. In tutta la sua carriera ha venduto oltre 25 milioni di dischi.<br>Noi dello Studio lo abbiamo omaggiato ricostruendo la storia della sua famiglia, grazie all&#8217;Archivio di Stato Civile di Rieti.<\/p>\n\n\n\n<p>CENNI STORICO-GENEALOGICI SUI BATTISTI<\/p>\n\n\n\n<p>Lucio Battisti nacque a Poggio Bustone (RI) alle 13.30 del 5 marzo 1943 (un giorno dopo rispetto al collega Lucio Dalla), nella casa di via Roma 40, secondo figlio di Alfiero, impiegato al dazio (1913 &#8211; 2008) e Dea Battisti, casalinga (18 aprile 1917 &#8211; 12 maggio 1983). La famiglia era completata dalla sorella Albarita (1946 &#8211; 2003), mentre il primogenito, anch&#8217;egli di nome Lucio (6 marzo 1940 &#8211; 26 maggio 1942), era morto in infanzia.<br>A Poggio Bustone, il cognome Battisti era ed \u00e8 tutt&#8217;ora il secondo pi\u00f9 diffuso, dopo Mostarda, infatti la ricostruzione del suo albero non \u00e8 stata facilissima, viste le tantissime omonimie, sebbene il paese in s\u00e9 contasse, tra la fine dell&#8217;ottocento e l&#8217;inizio del novecento, tra i 1300 e i 2000 abitanti.<br>La famiglia Battisti \u00e8 di umili origini, da quanto si evince dai documenti, erano dediti infatti nel campo della falegnameria (professione del nonno Matteo e del bisnonno Francesco) e ai lavori di campagna (molti dei collaterali erano contadini, soprattutto il trisavolo Matteo e il quatrisavolo Stefano).<br>Anche la madre di Lucio, Dea, era una Battisti. Non sono state trovate parentele dirette, poich\u00e9 Dea era figlia di Giovanni Battista Battisti, figlio a sua volta di Andrea Battisti, tutti di Poggio Bustone, anch&#8217;essi tutti falegnami.\u00a0<br>Sei curioso anche tu di conoscere nomi, luoghi, mestieri e curiosit\u00e0 dei tuoi antenati? Vuoi ricostruire la storia della tua famiglia con noi?<br>Contattaci per info: stu&#100;&#105;&#111;&#x61;&#x72;&#x61;&#x6c;&#x64;&#x69;cog&#101;&#110;&#101;&#97;&#x6c;&#x6f;&#x67;&#x69;&#x63;&#x6f;&#64;gm&#97;&#105;&#108;&#x2e;&#x63;&#x6f;&#x6d;  <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"920\" src=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/04\/albero-genealogico-lucio-battisti-1-1024x920.png\" alt=\"\" class=\"wp-image-902\" srcset=\"https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/04\/albero-genealogico-lucio-battisti-1-1024x920.png 1024w, https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/04\/albero-genealogico-lucio-battisti-1-300x269.png 300w, https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/04\/albero-genealogico-lucio-battisti-1-768x690.png 768w, https:\/\/www.rivistazoom.it\/wp-content\/uploads\/2020\/04\/albero-genealogico-lucio-battisti-1.png 1139w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">Articolo a cura di Lorenzo Cirelli<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 5 marzo c&#8217;\u00e8 stato il compleanno di Lucio Battisti (Poggio Bustone, 5 marzo 1943 \u2013 Milano, 9 settembre 1998)<\/p>\n<div class='the_champ_sharing_container the_champ_vertical_sharing the_champ_hide_sharing the_champ_bottom_sharing' style='width:44px;left: -10px;top: 100px;-webkit-box-shadow:none;box-shadow:none;' data-super-socializer-href=\"https:\/\/www.rivistazoom.it\"data-super-socializer-no-counts=\"1\"><div class=\"the_champ_sharing_ul\"><a style=\"font-size:24px!important;box-shadow:none;display:inline-block!important;font-size: 16px;padding: 0 4px;vertical-align:middle;display:inline;\" class=\"theChampSharingRound\"><span class=\"the_champ_square_count\">&nbsp;<\/span><div style=\"width:70px;height:35px;margin-bottom:9px !important;\" title=\"Total Shares\" class=\"theChampSharing theChampTCBackground\"><\/div><\/a><a class=\"the_champ_facebook\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Facebook\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#3c589a;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_facebook_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-5 -5 42 42\"><path d=\"M17.78 27.5V17.008h3.522l.527-4.09h-4.05v-2.61c0-1.182.33-1.99 2.023-1.99h2.166V4.66c-.375-.05-1.66-.16-3.155-.16-3.123 0-5.26 1.905-5.26 5.405v3.016h-3.53v4.09h3.53V27.5h4.223z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Zoom%20-%20&url=https%3A%2F%2Fwww.rivistazoom.it\" title=\"Twitter\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg the_champ_s__default the_champ_s_twitter\" style=\"background-color:#55acee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_twitter_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-4 -4 39 39\"><path d=\"M28 8.557a9.913 9.913 0 0 1-2.828.775 4.93 4.93 0 0 0 2.166-2.725 9.738 9.738 0 0 1-3.13 1.194 4.92 4.92 0 0 0-3.593-1.55 4.924 4.924 0 0 0-4.794 6.049c-4.09-.21-7.72-2.17-10.15-5.15a4.942 4.942 0 0 0-.665 2.477c0 1.71.87 3.214 2.19 4.1a4.968 4.968 0 0 1-2.23-.616v.06c0 2.39 1.7 4.38 3.952 4.83-.414.115-.85.174-1.297.174-.318 0-.626-.03-.928-.086a4.935 4.935 0 0 0 4.6 3.42 9.893 9.893 0 0 1-6.114 2.107c-.398 0-.79-.023-1.175-.068a13.953 13.953 0 0 0 7.55 2.213c9.056 0 14.01-7.507 14.01-14.013 0-.213-.005-.426-.015-.637.96-.695 1.795-1.56 2.455-2.55z\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_whatsapp\" href=\"https:\/\/api.whatsapp.com\/send?text=Zoom%20-%20 https%3A%2F%2Fwww.rivistazoom.it\" title=\"Whatsapp\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#55eb4c;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_whatsapp_count\">&nbsp;<\/span><svg style=\"display:block;\" focusable=\"false\" aria-hidden=\"true\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"100%\" height=\"100%\" viewBox=\"-6 -5 40 40\"><path class=\"the_champ_svg_stroke the_champ_no_fill\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\" d=\"M 11.579798566743314 24.396926207859085 A 10 10 0 1 0 6.808479557110079 20.73576436351046\"><\/path><path d=\"M 7 19 l -1 6 l 6 -1\" class=\"the_champ_no_fill the_champ_svg_stroke\" stroke=\"#fff\" stroke-width=\"2\" fill=\"none\"><\/path><path d=\"M 10 10 q -1 8 8 11 c 5 -1 0 -6 -1 -3 q -4 -3 -5 -5 c 4 -2 -1 -5 -1 -4\" fill=\"#fff\"><\/path><\/svg><\/span><\/a><a class=\"the_champ_button_instagram\" href=\"https:\/\/www.instagram.com\/Rivista_Zoom\" title=\"Instagram\" rel=\"nofollow noopener\" target=\"_blank\" style=\"font-size:24px!important;box-shadow:none;display:inline-block;vertical-align:middle\"><span class=\"the_champ_svg\" style=\"background-color:#53beee;width:70px;height:35px;display:inline-block;opacity:1;float:left;font-size:24px;box-shadow:none;display:inline-block;font-size:16px;padding:0 4px;vertical-align:middle;background-repeat:repeat;overflow:hidden;padding:0;cursor:pointer;box-sizing:content-box\"><span class=\"the_champ_square_count the_champ_instagram_count\">&nbsp;<\/span><svg style=\"display:block;\" version=\"1.1\" viewBox=\"-10 -10 148 148\" width=\"100%\" height=\"100%\" xml:space=\"preserve\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"><g><g><path d=\"M86,112H42c-14.336,0-26-11.663-26-26V42c0-14.337,11.664-26,26-26h44c14.337,0,26,11.663,26,26v44 C112,100.337,100.337,112,86,112z M42,24c-9.925,0-18,8.074-18,18v44c0,9.925,8.075,18,18,18h44c9.926,0,18-8.075,18-18V42 c0-9.926-8.074-18-18-18H42z\" fill=\"#fff\"><\/path><\/g><g><path d=\"M64,88c-13.234,0-24-10.767-24-24c0-13.234,10.766-24,24-24s24,10.766,24,24C88,77.233,77.234,88,64,88z M64,48c-8.822,0-16,7.178-16,16s7.178,16,16,16c8.822,0,16-7.178,16-16S72.822,48,64,48z\" fill=\"#fff\"><\/path><\/g><g><circle cx=\"89.5\" cy=\"38.5\" fill=\"#fff\" r=\"5.5\"><\/circle><\/g><\/g><\/svg><\/span><\/a><\/div><\/div>","protected":false},"author":1,"featured_media":902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[137,38,189,29,40],"_links":{"self":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/901"}],"collection":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":1,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/901\/revisions"}],"predecessor-version":[{"id":903,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/posts\/901\/revisions\/903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media\/902"}],"wp:attachment":[{"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/media?parent=901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/categories?post=901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rivistazoom.it\/index.php\/wp-json\/wp\/v2\/tags?post=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}